{"id":9417,"date":"2016-09-28T14:00:28","date_gmt":"2016-09-28T13:00:28","guid":{"rendered":"https:\/\/www.websdirect.es\/?p=9417"},"modified":"2016-09-28T14:00:28","modified_gmt":"2016-09-28T13:00:28","slug":"video-en-email-marketing-reinventa-la-forma-de-atraer-clientes","status":"publish","type":"post","link":"https:\/\/www.websdirect.es\/blog\/video-en-email-marketing-reinventa-la-forma-de-atraer-clientes\/","title":{"rendered":"Video en Email Marketing, reinventa la forma de atraer clientes"},"content":{"rendered":"<p>La inserci\u00f3n de <strong>v\u00eddeo en email marketing<\/strong> no solo supone una completa <strong>reinvenci\u00f3n en la forma de atraer a los clientes<\/strong>, sino tambi\u00e9n en uno de los recursos m\u00e1s valiosos para la industria de la publicidad online en estos momentos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9421 aligncenter\" src=\"https:\/\/www.websdirect.es\/blog\/wp-content\/uploads\/2016\/09\/videos-en-1.jpg\" alt=\"videos en\" width=\"588\" height=\"513\" \/><br \/>\n<!--more--><\/p>\n<p>El uso del <strong>v\u00eddeo<\/strong> <strong>en<\/strong> tus campa\u00f1as de <strong>email marketing<\/strong> es una manera eficaz de no pasar desapercibido en la Red y persuadir con \u00e9xito a tus clientes sobre el mensaje que deseas transmitir. Bien es cierto que la comercializaci\u00f3n mediante el v\u00eddeo no es un concepto nuevo, dado que en los \u00faltimos a\u00f1os las empresas se han servido de estas piezas audiovisuales para informar, entretener o educar a los principales interesados. El v\u00eddeo web, sin ir m\u00e1s lejos, se ha convertido en una de las herramientas m\u00e1s utilizadas por las peque\u00f1as y medianas empresas.<\/p>\n<h2>Persuade a tus clientes con v\u00eddeo en email marketing<\/h2>\n<p>El uso del <strong>v\u00eddeo en las acciones de email marketing<\/strong> es una opci\u00f3n a tener en cuenta para atraer a m\u00e1s clientes e incrementar su grado de fidelidad en nuestros servicios. El v\u00eddeo permite crear y compartir contenido con el p\u00fablico a un nivel de cercan\u00eda que un texto, muchas veces, no es capaz de alcanzar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9423 size-full\" title=\"Persuade a tus clientes con v\u00eddeo en email marketing\" src=\"https:\/\/www.websdirect.es\/blog\/wp-content\/uploads\/2016\/09\/ThinkstockPhotos-545676060-1.jpg\" alt=\"Persuade a tus clientes con v\u00eddeo en email marketing\" width=\"754\" height=\"464\" \/><\/p>\n<p>\u00danicamente hemos de acudir a estudios oficiales realizados al respecto para darnos cuenta de que la incorporaci\u00f3n de un<strong> v\u00eddeo en mensajes de correo electr\u00f3nico<\/strong> increment\u00f3 las tasas de apertura en un nada desde\u00f1able 5,6%, as\u00ed como el n\u00famero de clics en la friolera del casi 97%, unos datos que superan de manera considerable las tasas de apertura de los correos convencionales enviados por las marcas a sus clientes.<\/p>\n<p>Investigaciones, como las realizadas por Forrester Research, concluyen que los v\u00eddeos tambi\u00e9n tienen 50 veces m\u00e1s posibilidades de aparecer en la primera p\u00e1gina de los resultados de b\u00fasqueda que un contenido ausente de tales materiales multimedia. No obstante, al margen de esto \u00faltimo y volviendo a las campa\u00f1as de <strong>video en email marketing,<\/strong> se ha de tener muy presente que aquellas piezas audiovisuales en las que se explica detalladamente el funcionamiento de determinados productos resultan de especial inter\u00e9s para los usuarios que abren su correo electr\u00f3nico. Los clientes sienten que han invertido valiosamente su tiempo.<\/p>\n<p>Todo ello por no hablar de que el departamento de atenci\u00f3n al cliente ya no se ver\u00e1 saturado de preguntas t\u00edpicas por parte del usuario como las relativas al funcionamiento de un determinado producto. En este punto reside, en muchas ocasiones, el \u00e9xito de la inserci\u00f3n de <strong>v\u00eddeos en email marketing.\u00a0<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9424 size-full\" title=\"Persuade a tus clientes con v\u00eddeo en email marketing\" src=\"https:\/\/www.websdirect.es\/blog\/wp-content\/uploads\/2016\/09\/videos-1.jpg\" alt=\"Persuade a tus clientes con v\u00eddeo en email marketing\" width=\"661\" height=\"529\" \/><\/p>\n<p>Una de las principales complicaciones que puede suponer la introducci\u00f3n de un v\u00eddeo en un correo electr\u00f3nico se deba a la incompatibilidad de los proveedores de email para reproducirlo, dado que por motivos de seguridad algunas plataformas no aceptan el formato de dicho v\u00eddeo. Afortunadamente, hace unas semanas se puso en marcha una tecnolog\u00eda conocida como <strong>Viwomail,<\/strong> a trav\u00e9s de la cual es posible generar hasta un total de <strong>20 formatos de v\u00eddeo diferentes<\/strong> en tan solo unos minutos, detectando en tiempo real desde qu\u00e9 dispositivo, proveedor de correo y sistema operativo se est\u00e1 abriendo, as\u00ed como el formato id\u00f3neo para su reproducci\u00f3n (MP4, OGG o WebM).<\/p>\n<p>Muy diversas marcas nacionales e internacionales, dentro del sector de la moda, turismo, telecomunicaciones, seguros o sanidad se han sumado a la introducci\u00f3n de v\u00eddeos en email marketing, logrando <strong>aumentar su tasa de clics<\/strong> hasta en un 170% y<strong> sus ventas<\/strong> hasta un 60% por cada campa\u00f1a realizada.<\/p>\n<p><strong>Reinventa la forma de atraer a los clientes<\/strong> y mejora en cuestiones de branding con la inserci\u00f3n de <strong>v\u00eddeo en email marketing<\/strong>, la alternativa eficaz para convertir a tu empresa en un referente del sector.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La inserci\u00f3n de v\u00eddeo en email marketing no solo supone una completa reinvenci\u00f3n en la forma de atraer a los clientes, sino tambi\u00e9n en uno de los recursos\u2026<\/p>\n","protected":false},"author":1,"featured_media":9420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2,70],"tags":[14,64],"class_list":["post-9417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consultoria-marketing-digital","category-redes-sociales","tag-publicidad-internet","tag-video"],"jetpack_featured_media_url":"https:\/\/www.websdirect.es\/blog\/wp-content\/uploads\/2016\/09\/videos-contenido-1-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/posts\/9417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/comments?post=9417"}],"version-history":[{"count":0,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/posts\/9417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/media\/9420"}],"wp:attachment":[{"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/media?parent=9417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/categories?post=9417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/tags?post=9417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}