{"id":8750,"date":"2016-06-17T12:51:53","date_gmt":"2016-06-17T11:51:53","guid":{"rendered":"https:\/\/www.websdirect.es\/?p=8750"},"modified":"2016-06-17T12:51:53","modified_gmt":"2016-06-17T11:51:53","slug":"chatbots-un-paso-mas-en-atencion-al-cliente","status":"publish","type":"post","link":"https:\/\/www.websdirect.es\/blog\/chatbots-un-paso-mas-en-atencion-al-cliente\/","title":{"rendered":"Chatbots, un paso m\u00e1s en la atenci\u00f3n al cliente"},"content":{"rendered":"<p><strong>Un paso m\u00e1s en la atenci\u00f3n al cliente<\/strong>\u00a0se encuentra representado en los revolucionarios<strong> chatbots<\/strong>, la tecnolog\u00eda de asistencia virtual que viene del futuro para mejorar las relaciones de las empresas con sus clientes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8784 size-full\" title=\"Chatbots, un paso m\u00e1s en la atenci\u00f3n al cliente\" src=\"https:\/\/www.websdirect.es\/blog\/wp-content\/uploads\/2016\/06\/chat-bots-1.jpg\" alt=\"Chatbots, un paso m\u00e1s en la atenci\u00f3n al cliente\" width=\"754\" height=\"464\" \/><\/p>\n<p>Facebook, el rey del <a title=\"Social media marketing\" href=\"https:\/\/www.websdirect.es\/blog\/category\/redes-sociales\/\">Social Media<\/a>, anunci\u00f3 hace unas semanas la llegada inminente de los <strong>bots<\/strong> a Messenger. \u00bfEsto \u00faltimo supone el principio del fin para las aplicaciones de mensajer\u00eda instant\u00e1nea? Dise\u00f1ados como un software de inteligencia artificial, los <strong>bots<\/strong> se encargan de realizar una serie de tareas de manera aut\u00f3noma sin la mediaci\u00f3n de una persona como pueda ser, por ejemplo, fijar una fecha en el calendario, recoger o mostrar informaci\u00f3n o, incluso, reservar en un restaurante. Una de las variantes de este<strong> software<\/strong> m\u00e1s populares en estos momentos es lo que se conoce como <strong>chatbots,<\/strong> un robot capaz de simular una conversaci\u00f3n con una persona, de ah\u00ed que cada vez est\u00e9n m\u00e1s presentes en las aplicaciones de mensajer\u00eda instant\u00e1nea.<\/p>\n<h2><strong>\u00bfQu\u00e9 son los Chatbots?<\/strong><\/h2>\n<p>Los <strong>chatbots<\/strong> son empleados fundamentalmente para <strong>servicios de atenci\u00f3n al cliente<\/strong>. Lo cierto es que los bots ya fueron inventados hace la friolera de 50 a\u00f1os, cuando el matem\u00e1tico Alan Turing dise\u00f1\u00f3 la terminolog\u00eda que hoy es la encargada de hacer funcionar los equipos inform\u00e1ticos modernos y la Inteligencia Artificial (IA). No obstante, ha sido el auge de las apps de mensajer\u00eda m\u00f3vil, como es el caso de Facebook Messenger, WeChat o Slack, lo que ha provocado el hecho de que los bots vuelvan a cobrar importancia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8785 size-full\" title=\"\u00bfQu\u00e9 son los Chatbots?\" src=\"https:\/\/www.websdirect.es\/blog\/wp-content\/uploads\/2016\/06\/bots-1.jpg\" alt=\"\u00bfQu\u00e9 son los Chatbots?\" width=\"815\" height=\"429\" \/><\/p>\n<p>La llegada de los<strong> ChatBots <\/strong>a los<strong> servicios de atenci\u00f3n al cliente<\/strong> es un hecho, dada la confianza que un porcentaje cada vez mayor de empresas ha depositado en estos bots conversacionales capaces de ofrecer <strong>respuestas autom\u00e1ticas<\/strong> a entradas hechas por los propios clientes.<\/p>\n<p>Un servicio de chat muy similar a Whatsapp como <strong><em>\u00abKik\u00bb<\/em><\/strong>, muy popular en Estados Unidos, ha venido a revolucionar el mundo de la publicidad al permitir a los usuarios hablar con las marcas por medio de los robots antes mencionados. Cuatro de cada diez adolescentes estadounidenses son usuarios activos de este chatbot. Este \u00faltimo es solo un ejemplo de la altura a la que ha llegado el desarrollo de la tecnolog\u00eda en lo que al servicio de atenci\u00f3n al cliente se refiere.<\/p>\n<h2><strong>Chatbots, la atenci\u00f3n al cliente del futuro<\/strong><\/h2>\n<p>Lo que no cabe duda es que los <strong>Chatbots<\/strong> est\u00e1n redefiniendo de manera radical la manera en la que interaccionamos en nuestra vida diaria hasta el punto de que un porcentaje cada vez mayor de los usuarios no ha dudado en aprovechar las ventajas en cuanto a <strong>comodidad<\/strong> y <strong>ahorro de tiempo<\/strong> que ofrecen este tipo de tecnolog\u00edas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8786 size-full\" title=\"Chatbots, la atenci\u00f3n al cliente del futuro\" src=\"https:\/\/www.websdirect.es\/blog\/wp-content\/uploads\/2016\/06\/bots-conversando-1.jpg\" alt=\"Chatbots, la atenci\u00f3n al cliente del futuro\" width=\"683\" height=\"512\" \/><\/p>\n<p>En respuesta al crecimiento que han experimentado en los \u00faltimos a\u00f1os las <strong><a title=\"Desarrollo de aplicaciones m\u00f3viles\" href=\"https:\/\/www.websdirect.es\/blog\/empresa-desarrollo-web\/\">aplicaciones m\u00f3viles<\/a><\/strong> intuitivas en smartphones, las compa\u00f1\u00edas piensan en los asistentes virtuales para sus centros de contacto y como pilar fundamental dentro de su estrategia empresarial. Frente al descontento general que los Millennials muestran hacia los servicios de <strong>atenci\u00f3n al cliente<\/strong> convencionales, los<strong> chatbots<\/strong> se erigen como una alternativa a tener en cuenta para mejorar este tipo de funciones y satisfacer de un modo m\u00e1s eficaz las necesidades de estos nuevos tipos de consumidores.<\/p>\n<p>Esta clase de asistentes han extendido su influencia al campo de los <strong>recursos humanos,<\/strong> siendo<strong><em> \u00abMila\u00bb<\/em> <\/strong>uno de los ejemplos m\u00e1s representativos. Se trata de un asistente interactivo que cambia la manera en que los agentes y supervisores interaccionan entre s\u00ed, por no hablar de que ayuda a estos \u00faltimos a mejorar notablemente los requisitos del personal.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8789 size-full\" title=\"Chatbots en la atenci\u00f3n al cliente\" src=\"https:\/\/www.websdirect.es\/blog\/wp-content\/uploads\/2016\/06\/tus-chat-bots-1-1.jpg\" alt=\"Chatbots en la atenci\u00f3n al cliente\" width=\"724\" height=\"366\" \/><\/p>\n<p>Como se afirmaba desde un principio, los<strong> chatbots<\/strong> son<strong> un paso m\u00e1s en la atenci\u00f3n al cliente<\/strong> que las marcas\u00a0no han pasado por alto y que, en breve, se convertir\u00e1n en uno de los pilares fundamentales de la estrategia empresarial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un paso m\u00e1s en la atenci\u00f3n al cliente\u00a0se encuentra representado en los revolucionarios chatbots, la tecnolog\u00eda de asistencia virtual que viene del futuro para mejorar las relaciones de\u2026<\/p>\n","protected":false},"author":1,"featured_media":8783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[80],"tags":[82],"class_list":["post-8750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollo-apps","tag-aplicacion"],"jetpack_featured_media_url":"https:\/\/www.websdirect.es\/blog\/wp-content\/uploads\/2016\/06\/servicio-atencion-1-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/posts\/8750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/comments?post=8750"}],"version-history":[{"count":0,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/posts\/8750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/media\/8783"}],"wp:attachment":[{"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/media?parent=8750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/categories?post=8750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.websdirect.es\/blog\/wp-json\/wp\/v2\/tags?post=8750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}